{"id":3227,"date":"2022-12-09T15:33:00","date_gmt":"2022-12-09T14:33:00","guid":{"rendered":"https:\/\/www.eh-tique-media-tique.com\/?p=3227"},"modified":"2024-01-04T15:35:19","modified_gmt":"2024-01-04T14:35:19","slug":"le-tout-et-son-contraire","status":"publish","type":"post","link":"https:\/\/www.eh-tique-media-tique.com\/index.php\/2022\/12\/09\/le-tout-et-son-contraire\/","title":{"rendered":"Le Tout et son Contraire"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>A l\u2019ombre d\u2019un Hubris \u00e0 nul autre pareil&nbsp;!<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Macron \u00e0 l\u2019International&nbsp;?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Les Mots, les Gestes&nbsp;?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Je me demande souvent ce qui a pu pousser mon pays \u00e0 porter au pouvoir le Pr\u00e9sident actuel,&nbsp; une premi\u00e8re, puis une deuxi\u00e8me fois- il faut le faire&nbsp;! &#8211; sauf \u00e0 dire que notre \u00e9lite politique n\u2019\u00e9tait plus \u00e0 la hauteur des enjeux de pouvoir de la France, et qu\u2019en d\u00e9finitive ce Pr\u00e9sident \u00e9tait \u00e0 l\u2019image d\u2019un pays d\u00e9structur\u00e9, malade d\u2019institutions obsol\u00e8tes, et d\u2019une gouvernance nationale qui remettait son pouvoir \u00e0 l\u2019establishment parisien, cette engeance du fric, des faux semblants, du droit plus que du devoir, de l\u2019amollissement\u2026<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Un Pr\u00e9sident qui faute de filer la m\u00e9taphore, \u00e9gr\u00e8ne chaque jour des la\u00efus contradictoires, des \u00ab&nbsp;en m\u00eame temps,&nbsp;\u00bb changeants, comme c\u2019est \u00e0 nouveau le cas ces jours derniers avec les coupures d\u2019\u00e9lectricit\u00e9, et ses court-circuit r\u00e9p\u00e9t\u00e9s&nbsp;: une vraie cacophonie, mais avec la m\u00eame astuce, je tire un ch\u00e8que alors que la France n\u2019a plus d\u2019argent et qu\u2019elle vit \u00e0 cr\u00e9dit, et \u00e0 quel cr\u00e9dit\u2026<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Tout le monde ou presque, aujourd\u2019hui, connait le parcours de ce brillant sujet matern\u00e9 par une femme intelligente, un sujet qui se croit et se comporte toujours comme le premier de la classe, donnant des le\u00e7ons, un faiseur de paix sans paix, un baratineur du diable &#8211; le Grand D\u00e9bat &#8211; , un s\u00e9ducteur patent\u00e9 n\u2019h\u00e9sitant pas \u00e0 toucher famili\u00e8rement l\u2019autre pour faire croire \u00e0 une sorte d\u2019intimit\u00e9&nbsp;: on fait copain copain&#8230;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La photo Zelensky &#8211; Macron du 16 juin 2022 \u00e0 Kiev en dit plus long qu\u2019un long discours&nbsp;: Macron enlace Zelensky&nbsp;!!!<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Venons-en \u00e0 l\u2019Ukraine et \u00e0 l\u2019excellent papier de Madame Lasserre, dans le Figaro du 7 d\u00e9cembre 2022, intitul\u00e9 \u00ab&nbsp;Ukraine, les gaffes qui isolent la France&nbsp;\u00bb&nbsp;: la journaliste dresse un portrait sans concession du Pr\u00e9sident actuel, son langage inappropri\u00e9, o\u00f9 a-t-il appris la diplomatie, l\u2019histoire et les cultures des pays \u00e9trangers, notamment ceux de l\u2019Europe de l\u2019Est, d\u2019Afrique ou d\u2019Asie&nbsp;? De multiples faux-pas t\u00e9moignent de ses ignorances, et aujourd\u2019hui des jugements qu\u2019il porte sur des n\u00e9gociations possibles avec le nouveau tsar Poutine&nbsp;: donner des garanties \u00e0 la Russie en n\u00e9gociant avec Poutine le sanguinaire&nbsp;?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; A ses mots, un ancien pr\u00e9sident estonien a \u00ab&nbsp;d\u00e9pos\u00e9 trois lettres \u2026c\u2019est-\u00e0-dire, en substance \u00ab&nbsp;putain de merde&nbsp;\u00bb<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Macron incarne tout un ensemble de qualit\u00e9s et de d\u00e9fauts bien fran\u00e7ais, et je me contenterai de citer la conclusion de cet article qui les r\u00e9sume bien&nbsp;:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00ab&nbsp;un message\u2026 Illisible\u2026avec plusieurs illusions\u2026celle qui veut croire que les rapports personnels suffisent pour infl\u00e9chir les actes des dirigeants\u2026la faillite de son analyse russe\u2026 celle qui pr\u00e9tend faire de la France un faiseur de paix, alors qu\u2019elle n\u2019a plus les moyens, notamment militaires de ses ambitions, et que sa voix est de plus en plus isol\u00e9e en Europe. Celle, enfin, qui pense que la diplomatie peut convaincre Vladimir Poutine, alors que le Pr\u00e9sident russe ne comprend que le rapport de force.&nbsp;\u00bb<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Il a toujours cru qu\u2019il allait pouvoir s\u00e9duire les chefs d\u2019\u00c9tat \u00e9trangers de l\u2019Union Europ\u00e9enne comme il avait su le faire avec les membres de&nbsp; l\u2019establishment parisien\u2026<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>J\u2019ai toujours en t\u00eate l\u2019image d\u2019un Macron venu seul \u00e0 Moscou, \u00e0 une des extr\u00e9mit\u00e9s d\u2019une immense table blanche, au d\u00e9but de la guerre d\u2019Ukraine, au Kremlin, persuad\u00e9 sans doute qu\u2019il ne fallait pas manquer cette occasion de passer \u00e0 l\u2019histoire&nbsp;: oubli\u00e9e alors l\u2019Union Europ\u00e9enne par notre premier de la classe\u2026<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Alors gare Emmanuel, si l\u2019on en croit l\u2019Antiquit\u00e9 grecque, ton hubris immod\u00e9r\u00e9 risque fort&nbsp; d\u2019attirer la vengeance des Dieux&nbsp;!<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Penses quand m\u00eame \u00e0 la France&nbsp;!<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Jean Pierre Renaud&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Tous droits r\u00e9serv\u00e9s<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>PS&nbsp;: derni\u00e8re nouvelle, le cadeau de No\u00ebl d\u2019un Pr\u00e9sident dans le vent&nbsp;: des pr\u00e9servatifs gratuits pour les jeunes de 18 \u00e0 25 ans&nbsp;!!!<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A l\u2019ombre d\u2019un Hubris \u00e0 nul autre pareil&nbsp;! Macron \u00e0 l\u2019International&nbsp;? Les Mots, les Gestes&nbsp;? &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Je me demande souvent ce qui a pu pousser mon pays \u00e0 porter au pouvoir le Pr\u00e9sident actuel,&nbsp; une premi\u00e8re, puis une deuxi\u00e8me fois- il faut le faire&nbsp;! &#8211; sauf \u00e0 dire que notre \u00e9lite politique n\u2019\u00e9tait plus \u00e0 &hellip; <a href=\"https:\/\/www.eh-tique-media-tique.com\/index.php\/2022\/12\/09\/le-tout-et-son-contraire\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;Le Tout et son Contraire&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,7,6,5,4],"tags":[270,280],"class_list":["post-3227","post","type-post","status-publish","format-standard","hentry","category-actualites","category-communication","category-culture","category-histoire","category-politique","tag-france","tag-politique"],"_links":{"self":[{"href":"https:\/\/www.eh-tique-media-tique.com\/index.php\/wp-json\/wp\/v2\/posts\/3227","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eh-tique-media-tique.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eh-tique-media-tique.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eh-tique-media-tique.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eh-tique-media-tique.com\/index.php\/wp-json\/wp\/v2\/comments?post=3227"}],"version-history":[{"count":1,"href":"https:\/\/www.eh-tique-media-tique.com\/index.php\/wp-json\/wp\/v2\/posts\/3227\/revisions"}],"predecessor-version":[{"id":3228,"href":"https:\/\/www.eh-tique-media-tique.com\/index.php\/wp-json\/wp\/v2\/posts\/3227\/revisions\/3228"}],"wp:attachment":[{"href":"https:\/\/www.eh-tique-media-tique.com\/index.php\/wp-json\/wp\/v2\/media?parent=3227"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eh-tique-media-tique.com\/index.php\/wp-json\/wp\/v2\/categories?post=3227"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eh-tique-media-tique.com\/index.php\/wp-json\/wp\/v2\/tags?post=3227"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}